{"id":3340,"date":"2025-03-31T15:50:01","date_gmt":"2025-03-31T15:50:01","guid":{"rendered":"http:\/\/www.martincodax.com\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/"},"modified":"2025-06-27T09:57:09","modified_gmt":"2025-06-27T09:57:09","slug":"nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes","status":"publish","type":"post","link":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/","title":{"rendered":"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s"},"content":{"rendered":"<p style=\"text-align: justify;\"><div class=\"multimedia-img\">\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5645\" src=\"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/03\/ENOTURISMO-EN-BODEGAS-MART\u00cdN-C\u00d3DAX-1.jpg\" alt=\"ENOTURISMO EN BODEGAS MART\u00cdN C\u00d3DAX (1)\" width=\"4151\" height=\"2767\" \/><\/p>\n<p style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\"><article class=\"texto\">\n<p>Co obxectivo de consolidar \u00e1s R\u00edas Baixas como un referente do enoturismo, en Bodegas Mart\u00edn C\u00f3dax seguimos apostando por un abanico de actividades coidadosamente dese\u00f1adas. Experiencias que non s\u00f3 permiten descubrir os segredos dos nosos vi\u00f1os, sen\u00f3n tam\u00e9n mergullarse nas tradici\u00f3ns e a beleza natural da zona do Val do Saln\u00e9s.<\/p>\n<p>Este ano, a programaci\u00f3n de actividades ampl\u00edase e diversif\u00edcase para ofrecer aos visitantes unha infinidade de opci\u00f3ns que incl\u00faen visitas guiadas, catas maridadas, experiencias inmersivas e un contacto directo coa contorna. Xa sexa que se visite a adega por primeira vez ou que se sexa un habitual do Val do Saln\u00e9s,\u00a0estas propostas\u00a0convidan a descubrir a maxia de R\u00edas Baixas dende unha perspectiva \u00fanica.<\/p>\n<p style=\"text-align: justify;\"><\/article>\n<div class=\"multimedia-img\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5647\" src=\"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/03\/ENOTURISMO-EN-BODEGAS-MART\u00cdN-C\u00d3DAX-3.jpg\" alt=\"ENOTURISMO EN BODEGAS MART\u00cdN C\u00d3DAX (3)\" width=\"4977\" height=\"3318\" \/><\/p>\n<\/div>\n<p style=\"text-align: justify;\"><article class=\"texto\">\n<p style=\"text-align: justify;\"><strong>Un abanico de actividades para todos os gustos<\/strong><\/p>\n<p style=\"text-align: justify;\">Tres visitas guiadas diferentes, dese\u00f1adas para descubrir a orixe da adega e os segredos das nosas elaboraci\u00f3ns:<\/p>\n<ul>\n<li><strong>Orixe:<\/strong>\u00a0A visita fundamental \u00e1 adega, que permite co\u00f1ecer a nosa orixe e proceso de elaboraci\u00f3n. Culmina cunha cata comentada de dous vi\u00f1os 100% albari\u00f1o acompa\u00f1ados de dous queixos artes\u00e1ns galegos.<\/li>\n<li><strong>Ondas do Mar:<\/strong>\u00a0Unha experiencia sensorial que incl\u00fae tres vi\u00f1os, harmonizados con tres elaboraci\u00f3ns con produtos de proximidade, que nos conectan co mar e\u00a0coa zona.<\/li>\n<li><strong>Creaci\u00f3ns Singulares:<\/strong>\u00a0Visita exclusiva \u00e1 adega de investigaci\u00f3n, onde os visitantes gozar\u00e1n de catro vi\u00f1os de produci\u00f3n limitada maridados con elaboraci\u00f3ns gourmet, todo iso nun ambiente cheo de historia e creatividade.<\/li>\n<\/ul>\n<\/article>\n<p style=\"text-align: justify;\"><div class=\"multimedia-img\">\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5646\" src=\"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/03\/ENOTURISMO-EN-BODEGAS-MART\u00cdN-C\u00d3DAX-2.jpg\" alt=\"ENOTURISMO EN BODEGAS MART\u00cdN C\u00d3DAX (2)\" width=\"5143\" height=\"3429\" \/><\/p>\n<p style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\"><article class=\"texto\">\n<p><b>Vivir a contorna: experiencias \u00fanicas no Val do Saln\u00e9s<\/b><\/p>\n<p>En Bodegas Mart\u00edn C\u00f3dax queremos ir m\u00e1is al\u00f3 das visitas tradicionais, ofrecendo experiencias nas que os visitantes se converten en protagonistas.<\/p>\n<ul>\n<li><strong>Aprende a mariscar:<\/strong>\u00a0Sente a tradici\u00f3n das mariscadoras da R\u00eda de Arousa e experimenta a recolecci\u00f3n de mariscos, unha actividade que conecta ao visitante coa cultura local e o mar.<\/li>\n<li><strong>Os Tesouros da R\u00eda:<\/strong>\u00a0Merg\u00fallate no proceso de conservaci\u00f3n artesanal de produtos do mar nunha visita a unha conserveira local, unha experiencia \u00fanica que revela o sabor de Galicia.<\/li>\n<li><strong>O Mar en liberdade:<\/strong>\u00a0Goza dun paseo nunha embarcaci\u00f3n tradicional pola R\u00eda de Arousa, explorando a natureza que rodea a adega mentres sentes a conexi\u00f3n coa terra e o mar.<\/li>\n<\/ul>\n<p>Cada unha destas experiencias complem\u00e9ntase cunha visita guiada \u00e1 adega e unha cata maridada, brindando unha experiencia completa do vi\u00f1o, a gastronom\u00eda local e a contorna natural.<\/p>\n<\/article>\n<div class=\"multimedia-img\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5649\" src=\"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/06\/W8A5615-Editar-1-scaled.jpg\" alt=\"_W8A5615-Editar (1)\" width=\"3048\" height=\"4572\" \/><\/p>\n<\/div>\n<p style=\"text-align: justify;\"><article class=\"texto\">\n<p><strong>Catas con vistas \u00e1 R\u00eda de Arousa e un <em>wine bar<\/em> para os amantes do vi\u00f1o<\/strong><\/p>\n<p>Na nosa terraza, gozando das espectaculares vistas \u00e1 R\u00eda de Arousa, os visitantes poden gozar de catas \u00fanicas que permiten descubrir a alma de cada vi\u00f1o no seu lugar de orixe. Ademais, a adega conta cun <em>wine bar<\/em>, un punto de encontro perfecto para os amantes do vi\u00f1o, onde poder degustar todas as elaboraci\u00f3ns da adega, tanto na terraza como na nosa Barra Atl\u00e1ntica, nun ambiente relaxado e acolledor, sen necesidade de reserva previa.<\/p>\n<p>As<strong> Cantigas<\/strong> seguen sendo unha das experiencias m\u00e1is especiais, cunha selecci\u00f3n de vi\u00f1os dese\u00f1ada polo sumiller da adega. Cada cata est\u00e1 inspirada nun concepto do mundo do vi\u00f1o e busca espertar os sentidos mentres rende homenaxe \u00e1 cultura e tradici\u00f3ns galegas.<\/p>\n<p>Ao longo da tempada, iranse incorporando novas propostas de visitas e actividades, ademais dos eventos estivais, que completar\u00e1n a ampla oferta de Bodegas Mart\u00edn C\u00f3dax para a tempada de enoturismo de 2025.<\/p>\n<p>Toda a informaci\u00f3n sobre cada unha das actividades de enoturismo est\u00e1 dispo\u00f1ible na nosa web: https:\/\/tienda.martincodax.com\/.<\/p>\n<\/article>\n<p style=\"text-align: justify;\"><div class=\"multimedia-img\">\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5648\" src=\"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/03\/ENOTURISMO-EN-BODEGAS-MART\u00cdN-C\u00d3DAX-4.jpg\" alt=\"ENOTURISMO EN BODEGAS MART\u00cdN C\u00d3DAX (4)\" width=\"5406\" height=\"3604\" \/><\/p>\n<p style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"Co obxectivo de consolidar \u00e1s R\u00edas Baixas como un referente do enoturismo, en Bodegas Mart\u00edn C\u00f3dax seguimos apostando por un abanico de actividades coidadosamente dese\u00f1adas. Experiencias que non s\u00f3 permiten descubrir os segredos dos nosos vi\u00f1os, sen\u00f3n tam\u00e9n mergullarse nas tradici\u00f3ns e a beleza natural da zona do Val do Saln\u00e9s. Este ano, a programaci\u00f3n...","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-3340","post","type-post","status-publish","format-standard","hentry","category-noticias-gl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s - Mart\u00edn C\u00f3dax<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s - Mart\u00edn C\u00f3dax\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/\" \/>\n<meta property=\"og:site_name\" content=\"Mart\u00edn C\u00f3dax\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BodegasMartinCodax\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-31T15:50:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-27T09:57:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/06\/W8A5615-Editar-1-scaled.jpg\" \/>\n<meta name=\"author\" content=\"martincodax\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"martincodax\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/\"},\"author\":{\"name\":\"martincodax\",\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/#\\\/schema\\\/person\\\/1f81629eb18c9297e0711c0bd21b4c6f\"},\"headline\":\"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s\",\"datePublished\":\"2025-03-31T15:50:01+00:00\",\"dateModified\":\"2025-06-27T09:57:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/\"},\"wordCount\":653,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.martincodax.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/W8A5615-Editar-1-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/\",\"url\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/\",\"name\":\"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s - Mart\u00edn C\u00f3dax\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.martincodax.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/W8A5615-Editar-1-scaled.jpg\",\"datePublished\":\"2025-03-31T15:50:01+00:00\",\"dateModified\":\"2025-06-27T09:57:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.martincodax.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/W8A5615-Editar-1-scaled.jpg\",\"contentUrl\":\"http:\\\/\\\/www.martincodax.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/W8A5615-Editar-1-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/\",\"name\":\"Bodegas Mart\u00edn C\u00f3dax. Tienda online vino albari\u00f1o, enoturismo y eventos - Bodegas Mart\u00edn C\u00f3dax\",\"description\":\"Tienda online de las bodegas Mart\u00edn C\u00f3dax. Vino albari\u00f1o D.O. R\u00edas Baixas, aguardiente, licor caf\u00e9, entradas Os Xoves de C\u00f3dax, circuitos de enoturismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/#organization\",\"name\":\"Bodegas Mart\u00edn C\u00f3dax\",\"alternateName\":\"Mart\u00edn C\u00f3dax\",\"url\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.martincodax.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Logo-Martin-Codax-negro.png\",\"contentUrl\":\"https:\\\/\\\/www.martincodax.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Logo-Martin-Codax-negro.png\",\"width\":984,\"height\":192,\"caption\":\"Bodegas Mart\u00edn C\u00f3dax\"},\"image\":{\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BodegasMartinCodax\",\"https:\\\/\\\/www.instagram.com\\\/bodmartincodax\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/#\\\/schema\\\/person\\\/1f81629eb18c9297e0711c0bd21b4c6f\",\"name\":\"martincodax\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80d843f39f6270a1d6f820b7b4534a043360800347804fb6385cc00ee3c48290?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80d843f39f6270a1d6f820b7b4534a043360800347804fb6385cc00ee3c48290?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80d843f39f6270a1d6f820b7b4534a043360800347804fb6385cc00ee3c48290?s=96&d=mm&r=g\",\"caption\":\"martincodax\"},\"url\":\"https:\\\/\\\/www.martincodax.com\\\/gl\\\/author\\\/martincodax\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s - Mart\u00edn C\u00f3dax","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/","og_locale":"gl_ES","og_type":"article","og_title":"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s - Mart\u00edn C\u00f3dax","og_url":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/","og_site_name":"Mart\u00edn C\u00f3dax","article_publisher":"https:\/\/www.facebook.com\/BodegasMartinCodax","article_published_time":"2025-03-31T15:50:01+00:00","article_modified_time":"2025-06-27T09:57:09+00:00","og_image":[{"url":"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/06\/W8A5615-Editar-1-scaled.jpg","type":"","width":"","height":""}],"author":"martincodax","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"martincodax","Tempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/#article","isPartOf":{"@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/"},"author":{"name":"martincodax","@id":"https:\/\/www.martincodax.com\/gl\/#\/schema\/person\/1f81629eb18c9297e0711c0bd21b4c6f"},"headline":"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s","datePublished":"2025-03-31T15:50:01+00:00","dateModified":"2025-06-27T09:57:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/"},"wordCount":653,"commentCount":0,"publisher":{"@id":"https:\/\/www.martincodax.com\/gl\/#organization"},"image":{"@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/#primaryimage"},"thumbnailUrl":"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/06\/W8A5615-Editar-1-scaled.jpg","articleSection":["Noticias"],"inLanguage":"gl-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/","url":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/","name":"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s - Mart\u00edn C\u00f3dax","isPartOf":{"@id":"https:\/\/www.martincodax.com\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/#primaryimage"},"image":{"@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/#primaryimage"},"thumbnailUrl":"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/06\/W8A5615-Editar-1-scaled.jpg","datePublished":"2025-03-31T15:50:01+00:00","dateModified":"2025-06-27T09:57:09+00:00","breadcrumb":{"@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/#primaryimage","url":"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/06\/W8A5615-Editar-1-scaled.jpg","contentUrl":"http:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/06\/W8A5615-Editar-1-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.martincodax.com\/gl\/nova-tempada-de-enoturismo-experiencias-unicas-para-gozar-do-vino-e-da-contorna-do-val-do-salnes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.martincodax.com\/gl\/"},{"@type":"ListItem","position":2,"name":"Nova tempada de enoturismo. Experiencias \u00fanicas para gozar do vi\u00f1o e da contorna do Val do Saln\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.martincodax.com\/gl\/#website","url":"https:\/\/www.martincodax.com\/gl\/","name":"Bodegas Mart\u00edn C\u00f3dax. Tienda online vino albari\u00f1o, enoturismo y eventos - Bodegas Mart\u00edn C\u00f3dax","description":"Tienda online de las bodegas Mart\u00edn C\u00f3dax. Vino albari\u00f1o D.O. R\u00edas Baixas, aguardiente, licor caf\u00e9, entradas Os Xoves de C\u00f3dax, circuitos de enoturismo.","publisher":{"@id":"https:\/\/www.martincodax.com\/gl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.martincodax.com\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.martincodax.com\/gl\/#organization","name":"Bodegas Mart\u00edn C\u00f3dax","alternateName":"Mart\u00edn C\u00f3dax","url":"https:\/\/www.martincodax.com\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.martincodax.com\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/02\/Logo-Martin-Codax-negro.png","contentUrl":"https:\/\/www.martincodax.com\/wp-content\/uploads\/2025\/02\/Logo-Martin-Codax-negro.png","width":984,"height":192,"caption":"Bodegas Mart\u00edn C\u00f3dax"},"image":{"@id":"https:\/\/www.martincodax.com\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BodegasMartinCodax","https:\/\/www.instagram.com\/bodmartincodax\/"]},{"@type":"Person","@id":"https:\/\/www.martincodax.com\/gl\/#\/schema\/person\/1f81629eb18c9297e0711c0bd21b4c6f","name":"martincodax","image":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/80d843f39f6270a1d6f820b7b4534a043360800347804fb6385cc00ee3c48290?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80d843f39f6270a1d6f820b7b4534a043360800347804fb6385cc00ee3c48290?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80d843f39f6270a1d6f820b7b4534a043360800347804fb6385cc00ee3c48290?s=96&d=mm&r=g","caption":"martincodax"},"url":"https:\/\/www.martincodax.com\/gl\/author\/martincodax\/"}]}},"_links":{"self":[{"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/posts\/3340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/comments?post=3340"}],"version-history":[{"count":1,"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/posts\/3340\/revisions"}],"predecessor-version":[{"id":3341,"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/posts\/3340\/revisions\/3341"}],"wp:attachment":[{"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/media?parent=3340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/categories?post=3340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.martincodax.com\/gl\/wp-json\/wp\/v2\/tags?post=3340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}